{"id":1408,"date":"2024-04-09T13:39:23","date_gmt":"2024-04-09T11:39:23","guid":{"rendered":"https:\/\/grenierdecourbevoie.fr\/?p=1408"},"modified":"2024-04-09T13:39:24","modified_gmt":"2024-04-09T11:39:24","slug":"la-naufragee-de-la-tour-eiffel","status":"publish","type":"post","link":"https:\/\/grenierdecourbevoie.fr\/index.php\/2024\/04\/09\/la-naufragee-de-la-tour-eiffel\/","title":{"rendered":"La naufrag\u00e9e de la Tour Eiffel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">C\u2019\u00e9tait en janvier, au milieu d\u2019une journ\u00e9e bien ensoleill\u00e9e, qu\u2019arriva la b\u00eatise du jour.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma grand-m\u00e8re s\u2019\u00e9tait dit qu\u2019elle avait envie de se promener. Quand elle vit la Tour Eiffel, elle pensa que vu la taille du monument, il y avait un long chemin \u00e0 parcourir. Elle se dirigea dans sa direction sans trop r\u00e9fl\u00e9chir. Elle se rendit vite compte que beaucoup d\u2019immeubles bloquaient sa route.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heureusement, elle consulta le GPS sans tarder. Elle suivit les indications du GPS sans pr\u00eater attention au temps du trajet (1h30 de marche, donc environ 2h30 de promenade) et \u00e0 la distance (6,5 km environ).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois arriv\u00e9e, apr\u00e8s avoir pris quelques selfies, elle n\u2019avait plus assez de batterie pour utiliser le GPS pendant 2h30. Elle voulut prendre un bus, mais elle n\u2019avait pas pris un centime, elle nous envoya alors un SMS pour nous demander de quoi payer son ticket et nous fin\u00eemes par aller la r\u00e9cup\u00e9rer en voiture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019\u00e9tait en janvier, au milieu d\u2019une journ\u00e9e bien ensoleill\u00e9e, qu\u2019arriva la b\u00eatise du jour. Ma grand-m\u00e8re s\u2019\u00e9tait dit qu\u2019elle avait envie de se promener. Quand elle vit la Tour Eiffel, elle pensa que vu la taille du monument, il y avait un long chemin \u00e0 parcourir. Elle se dirigea dans sa direction sans trop r\u00e9fl\u00e9chir. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1484,244,1483],"class_list":["post-1408","post","type-post","status-publish","format-standard","hentry","category-non-classe","tag-gps","tag-perdu","tag-tour-eiffel"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1408"}],"version-history":[{"count":1,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1408\/revisions"}],"predecessor-version":[{"id":1409,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1408\/revisions\/1409"}],"wp:attachment":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}