{"id":144,"date":"2022-10-15T16:58:17","date_gmt":"2022-10-15T14:58:17","guid":{"rendered":"http:\/\/grenierdecourbevoie.fr\/?p=144"},"modified":"2022-11-01T18:29:27","modified_gmt":"2022-11-01T17:29:27","slug":"la-petite-fille-et-la-guerre","status":"publish","type":"post","link":"https:\/\/grenierdecourbevoie.fr\/index.php\/2022\/10\/15\/la-petite-fille-et-la-guerre\/","title":{"rendered":"La petite fille et la guerre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Je suis n\u00e9e \u00e0 Kilford, puis je suis all\u00e9e \u00e0 l\u2019\u00e9cole du Cayla, c\u00f4t\u00e9 filles, bien s\u00fbr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1943, ma m\u00e8re est retourn\u00e9e \u00e0 Kilford pour accoucher de ma petite s\u0153ur et elle m\u2019a racont\u00e9 qu\u2019entre la faim et le froid, c\u2019\u00e9tait un cauchemar absolu. Aucune m\u00e8re de famille n\u2019avait de lait parce qu\u2019elles \u00e9taient sous-aliment\u00e9es. Il n\u2019y avait pas de gaz \u00e0 cause du bombardement de f\u00e9vrier et on apportait pour les nourrissons des biberons froids.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019avais quatre ans, je me souviens que quand il y avait une alerte, mon p\u00e8re me prenait dans ses bras pour descendre dans l\u2019abri et un voisin, qui avait fait la guerre de 14, tenait au-dessus de moi une valise pour \u00e9viter que des gravats ne tombent sur moi. La nuit, je guettais avec beaucoup d\u2019angoisse et quand l\u2019alerte sonnait, j\u2019\u00e9tais la premi\u00e8re \u00e0 le crier \u00e0 mes parents<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je suis all\u00e9e \u00e0 la maternelle mais tr\u00e8s peu parce que j\u2019ai \u00e9t\u00e9 \u00e9vacu\u00e9e en Auvergne chez mes grands-parents qui \u00e9taient retourn\u00e9s au pays dans le sud du Cantal. L\u00e0-bas, il y avait des poules et des cochons. Cet \u00e9t\u00e9-l\u00e0 ils nt \u00e9vacu\u00e9s les enfants de Courbevoie et mon p\u00e8re qui \u00e9tait directeur d\u2019\u00e9cole a \u00e9t\u00e9 charg\u00e9 d\u2019un groupe du Cayla et peut-\u00eatre d\u2019autres \u00e9coles. On est partis dans un petit village au bord du Lot entre Cajarc et Cahors, \u00e0 Saint-Martin-Labouval. On y est rest\u00e9s de juillet 43 \u00e0 mai 45.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y avait une belle maison qu\u2019on appelait le Ch\u00e2teau avec un grand parc devant et derri\u00e8re un immense potager.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous habitions dans la maison de gardiens que le propri\u00e9taire avait mis \u00e0 notre disposition.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon petit fr\u00e8re y est n\u00e9 en 1945.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants \u00e9taient plac\u00e9s dans des familles. Mon p\u00e8re leur rendait visite \u00e0 v\u00e9lo r\u00e9guli\u00e8rement pour v\u00e9rifier que tout allait bien. Il y a eu des \u00e9pid\u00e9mies de gale, d\u2019imp\u00e9tigo, de choses comme \u00e7a et les enfants venaient chez nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Saint-Martin-Labouval, je me souviens tr\u00e8s bien des passages d\u2019Allemands, ceux qui seront responsables des fameux 99 pendus de Tulle juste apr\u00e8s. On les a vu d\u00e9ferler sur la petite route, ils ont encercl\u00e9 le village au lance-flamme et ils ont ex\u00e9cut\u00e9 le maire, l\u2019instituteur et le cur\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon p\u00e8re \u00e9tait justement parti en tourn\u00e9e \u00e0 v\u00e9lo et heureusement, il a entendu une colonne arriver et il s\u2019est jet\u00e9 \u00e0 plat ventre dans le foss\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes revenus \u00e0 Courbevoie pour la rentr\u00e9e 45.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mes parents n\u2019avaient plus un sou parce que les salaires n\u2019avaient pas chang\u00e9 depuis des ann\u00e9es et mon p\u00e8re a d\u00e9cid\u00e9 de prendre en charge une colonie de vacances de la ville pour gagner quelques sous. C\u2019\u00e9tait \u00e0 Radepont dans l\u2019Eure \u00e0 c\u00f4t\u00e9 de Fleury-sur-Andelle. Il y a eu un ou deux cas de dipht\u00e9rie. Mon p\u00e8re \u00e9tait forc\u00e9ment en contact avec les gosses. Les enfants n\u2019\u00e9taient vaccin\u00e9s qu\u2019\u00e0 partir de deux ans \u00e0 l\u2019\u00e9poque et mon petit fr\u00e8re qui avait treize mois a \u00e9t\u00e9 contamin\u00e9 et il est mort en novembre. L\u2019apr\u00e8s-guerre a \u00e9t\u00e9 tr\u00e8s sombre chez nous.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je suis n\u00e9e \u00e0 Kilford, puis je suis all\u00e9e \u00e0 l\u2019\u00e9cole du Cayla, c\u00f4t\u00e9 filles, bien s\u00fbr. En 1943, ma m\u00e8re est retourn\u00e9e \u00e0 Kilford pour accoucher de ma petite s\u0153ur et elle m\u2019a racont\u00e9 qu\u2019entre la faim et le froid, c\u2019\u00e9tait un cauchemar absolu. Aucune m\u00e8re de famille n\u2019avait de lait parce qu\u2019elles \u00e9taient [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,24,14],"tags":[142,172,74,141,166,165,162,168,161,167,170,164,169,163,171],"class_list":["post-144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enfance","category-guerre","category-temoignages","tag-142","tag-172","tag-allemand","tag-bombardement","tag-cahors","tag-cajarc","tag-cantal","tag-cayla","tag-das-reich","tag-ecole","tag-instituteur","tag-lot","tag-radepont","tag-saint-martin-labouval","tag-tulle"],"jetpack_featured_media_url":"https:\/\/grenierdecourbevoie.fr\/wp-content\/uploads\/2022\/10\/IMG_20220518_112131.jpg","_links":{"self":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":2,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"predecessor-version":[{"id":1838,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/posts\/144\/revisions\/1838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/media\/688"}],"wp:attachment":[{"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenierdecourbevoie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}